{"id":4298,"count":9,"description":"","link":"https:\/\/blogs.avui.cat\/jaumepubill\/category\/literatura\/blogs-que-segueixo\/","name":"Alguns blogs interessants...","slug":"blogs-que-segueixo","taxonomy":"category","parent":440,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.avui.cat\/jaumepubill\/wp-json\/wp\/v2\/categories\/4298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.avui.cat\/jaumepubill\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.avui.cat\/jaumepubill\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.avui.cat\/jaumepubill\/wp-json\/wp\/v2\/categories\/440"}],"wp:post_type":[{"href":"https:\/\/blogs.avui.cat\/jaumepubill\/wp-json\/wp\/v2\/posts?categories=4298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}